{"id":160547,"date":"2026-05-18T12:03:46","date_gmt":"2026-05-18T10:03:46","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/"},"modified":"2026-07-15T03:05:46","modified_gmt":"2026-07-15T01:05:46","slug":"earthdreamers-lodge-wochenende-en-ro-427049","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/","title":{"rendered":"Earthdreamers Lodge Wochenende&#8211;en"},"content":{"rendered":"<h3>&#8220;Wer bin ich? Woher komme ich und wohin gehe ich, wenn ich sterbe? Und warum \u00fcberhaupt bin ich da?&#8221;<\/h3>\n<p>Vielleicht sind es diese urmenschlichen und uralten Fragen, die dich aufbrechen lassen zu neuen Ufern, mit dem klaren Gef\u00fchl im Bauch, dass da \u00abmehr\u00bb sein muss als das, was du in deinem eingeschliffenen Alltag erlebst.<\/p>\n<p>Der \u00abSweet Medicine Sundance\u00bb-Weg bietet jahrtausendealtes Wissen aus S\u00fcd-, Mittel- und Nordamerika an, das uns echtes menschliches Wachstum erm\u00f6glicht. Denn die Grundlage f\u00fcr positive Ver\u00e4nderungen auf unserer wundersch\u00f6nen Erde sind wir und als allererstes unser Umgang mit uns selbst. Wenn wir uns selbst (er)kennen, sind wir f\u00e4hig, uns wahrhaft zu verbinden mit der Welt um uns herum, und dann k\u00f6nnen wir Heilung f\u00fcr die Erde und f\u00fcr andere zur Verf\u00fcgung stellen.<\/p>\n<p>**<\/p>\n<p>In diesem Kurs treffen sich Lehrlinge des \u00abSweet Medicine Sundance\u00bb-Weges, die bereits zwei oder drei Jahre auf dem Weg unterwegs sind. <\/p>\n<p>Wir verbinden uns tiefer mit den Welten von Grossmutter Erde \u2013 mit Mineralien, Pflanzen, Tieren und Ahnen \u2013 und entdecken, wie sie uns darin unterst\u00fctzen, als gl\u00fcckliche Menschen ganz und gar auf der Erde zu Hause zu sein. Wir widmen uns der Selbsterforschung und lernen die G\u00f6ttin \u00abQuetzal\u00bb kennen, die Lehrerin  von Leben, Tod und Wiedergeburt. Sie fordert uns heraus, in gr\u00f6ssere Zyklen von Ver\u00e4nderung einzutreten und ein f\u00fcr allemal Schluss zu machen mit Mustern, die uns trennen von unserer Nat\u00fcrlichkeit und unserem Wachstumspotenzial.<\/p>\n<p>Immer wieder gehen wir in die Natur, die uns als allergr\u00f6sste Lehrerin darin unterst\u00fctzt, in den Fluss des Lebens einzutauchen, Schmerzen aus der Vergangenheit loszulassen und uns voller Begeisterung auf das Jetzt einzulassen. Nebst Teachings und praktischen Erfahrungen draussen in der Natur widmen wir viel Zeit der Integration des Erlebten und dem Austausch mit- und untereinander. <\/p>\n<p>**<\/p>\n<p>Falls du noch keine Erfahrung auf dem \u00abSweet Medicine Sundance\u00bb-Weg hast und mehr wissen m\u00f6chtest, dann schau dir unser Angebot auf unserer Webseite an: www.earthdreamers.ch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Wer bin ich? Woher komme ich und wohin gehe ich, wenn ich sterbe? Und warum \u00fcberhaupt bin ich da?&#8221; Vielleicht sind es diese urmenschlichen und uralten Fragen, die dich aufbrechen lassen zu neuen Ufern, mit dem klaren Gef\u00fchl im Bauch, dass da \u00abmehr\u00bb sein muss als das, was du in deinem eingeschliffenen Alltag erlebst. Der [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-160547","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Earthdreamers Lodge Wochenende-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Earthdreamers Lodge Wochenende-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"&#8220;Wer bin ich? Woher komme ich und wohin gehe ich, wenn ich sterbe? Und warum \u00fcberhaupt bin ich da?&#8221; Vielleicht sind es diese urmenschlichen und uralten Fragen, die dich aufbrechen lassen zu neuen Ufern, mit dem klaren Gef\u00fchl im Bauch, dass da \u00abmehr\u00bb sein muss als das, was du in deinem eingeschliffenen Alltag erlebst. Der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T01:05:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/earthdreamers-lodge-wochenende-en-ro-427049\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/earthdreamers-lodge-wochenende-en-ro-427049\\\/\",\"name\":\"Earthdreamers Lodge Wochenende-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-05-18T10:03:46+00:00\",\"dateModified\":\"2026-07-15T01:05:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/earthdreamers-lodge-wochenende-en-ro-427049\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/earthdreamers-lodge-wochenende-en-ro-427049\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/earthdreamers-lodge-wochenende-en-ro-427049\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Earthdreamers Lodge Wochenende&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Earthdreamers Lodge Wochenende-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/","og_locale":"en_US","og_type":"article","og_title":"Earthdreamers Lodge Wochenende-en - Kientalerhof","og_description":"&#8220;Wer bin ich? Woher komme ich und wohin gehe ich, wenn ich sterbe? Und warum \u00fcberhaupt bin ich da?&#8221; Vielleicht sind es diese urmenschlichen und uralten Fragen, die dich aufbrechen lassen zu neuen Ufern, mit dem klaren Gef\u00fchl im Bauch, dass da \u00abmehr\u00bb sein muss als das, was du in deinem eingeschliffenen Alltag erlebst. Der [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/","og_site_name":"Kientalerhof","article_modified_time":"2026-07-15T01:05:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/","name":"Earthdreamers Lodge Wochenende-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-05-18T10:03:46+00:00","dateModified":"2026-07-15T01:05:46+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/earthdreamers-lodge-wochenende-en-ro-427049\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Earthdreamers Lodge Wochenende&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/160547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=160547"}],"version-history":[{"count":2,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/160547\/revisions"}],"predecessor-version":[{"id":160896,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/160547\/revisions\/160896"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=160547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}