{"id":159751,"date":"2026-03-31T12:04:58","date_gmt":"2026-03-31T10:04:58","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/"},"modified":"2026-05-13T03:04:58","modified_gmt":"2026-05-13T01:04:58","slug":"mg-2-nervensystem-b-wetzikon-en-27850012","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/","title":{"rendered":"MG 2 &#8211; Nervensystem B | Wetzikon&#8211;en"},"content":{"rendered":"<h3>Medizinische Grundlagen 2 &#8211; Nervensystem B<\/h3>\n<h2>Lerninhalte<\/h2>\n<p>In diesem Kurs erg\u00e4nzen wir unser inneres Bild aus dem Kurs Nervensystems A um die Blut- und Liquorzirkulation, die Hirnnerven und die Sinnesorgane, inkl. der Haut. Was passiert bei einem Hirnschlag? Was tut eigentlich weh bei Kopfschmerzen? Auch die Anatomie der Sinnesorgane leiten wir aus der Embryologie her, vom Einfachen zum Komplexen. So verstehen wir auch den Aufbau des Auges nach dem Zwiebelschalenprinzip. Weshalb sollte man nach dem 45. bis 50. Lebensjahr ab und zu den Augendruck kontrollieren lassen? Wie erkenne ich eine b\u00f6sartige Hautver\u00e4nderung? Weiter erhalten wir einen historischen \u00dcberblick der wichtigsten Richtungen der Psychologie und betrachten verschiedene psychische St\u00f6rungen wie Schizophrenie, Depression, Manie, u.a.<\/p>\n<ul>\n<li>Grundwissen der Anatomie, Physiologie, Pathologie, Zytologie, Histologie und Pharmakologie des Nervensystems Teil B und der Sinnesorgane<\/li>\n<li>Herleitung der Anatomie aus der Embryologie<\/li>\n<li>Sinnesorgane und Haut<\/li>\n<li>3D-Visualisierung des Nervensystems und der Sinnesorgane<\/li>\n<li>Psychologie und psychische St\u00f6rungen<\/li>\n<\/ul>\n<h2>Lernziele<\/h2>\n<p>Die Teilnehmenden sind in der Lage<\/p>\n<ul>\n<li>\teine schematische Skizze des Auges nach dem Zwiebelschalenprinzip anzufertigen und die verschiedenen Schichten zu beschriften und deren Funktion kurz zu erl\u00e4utern<\/li>\n<li>\tdie Schichten der Haut und deren Anhangsgebilde zu benennen<\/li>\n<li>\tdrei Funktionen der Haut aufzuz\u00e4hlen<\/li>\n<li>\tdie ABCDE Regel an vorgelegten Hautver\u00e4nderungen anzuwenden und die richtigen Massnahmen zu treffen<\/li>\n<li>\teine schematische Skizze des H\u00f6r- und Gleichgewichtsorgans zu beschriften und die Funktionsweise zu erkl\u00e4ren<\/li>\n<li>\tdie Leitsymptome der besprochenen Krankheiten und deren Therapie (inkl. Pharmakologie) kurz zu erl\u00e4utern<\/li>\n<li>\tdrei verschiedene Pers\u00f6nlichkeiten aus der Geschichte der Psychologie mit der dazugeh\u00f6rigen Therapieform zu nennen<\/li>\n<li>\tdie wichtigsten Merkmale der obigen drei von dir ausgew\u00e4hlten Therapieformen zu beschreiben<\/li>\n<li>\tzwei verschiedene Gebiete der Psychologie zu nennen<\/li>\n<li>\taufgelistete Merkmale zu einer Pers\u00f6nlichkeitsst\u00f6rung als &#8220;zutreffend&#8221; oder &#8220;nicht zutreffend&#8221; zu bewerten<\/li>\n<li>\tden Unterschied zwischen psychosomatischen und somatoformen St\u00f6rungen zu beschreiben, bzw. letztere beiden St\u00f6rungen zu definieren und Beispiele zu nennen<\/li>\n<li>\tdas Prinzip des &#8220;multikausalen Denkens&#8221; bzw. &#8220;biopsychosozialen Ursachenmusters&#8221; zu beschreiben<\/li>\n<li>\tdas Konzept der Alexithymie anhand eines Beispieles zu beschreiben<\/li>\n<li>\tdie kausale Kette von der Psyche bis zur Somatisierung bzw. Organmanifestation bzw. K\u00f6rperhaltung zu beschreiben<\/li>\n<li>\tdie wichtigsten Fakten (Leitsymptome, etc.) der besprochenen psychischen Krankheiten und deren Therapie (inkl. Pharmakologie) kurz zu erl\u00e4utern<\/li>\n<\/ul>\n<h2>Zielgruppe<\/h2>\n<p>Dieser Kurs richtet sich an angehende K\u00f6rpertherapeuten\/innen (Shiatsu, Craniosacral Therapie, Massage, Akupressur u.a.) und weitere Interessierte. Die Inhalte entsprechen den Anforderungen des Schweizer Gesundheitswesens. F\u00fcr Menschen ohne medizinische Ausbildung ist dieses Seminar ein vortrefflicher Einstieg in die vielschichtige Welt der K\u00f6rperarbeit und ins anatomische Grundwissen. Medizinisch ausgebildete Personen k\u00f6nnen von der ganzheitlichen, Methoden \u00fcbergreifenden Sicht profitieren. <\/p>\n<h2>Voraussetzungen<\/h2>\n<p>Keine besonderen Vorkenntnisse erforderlich.<br \/>\nDer Kurs bietet eine ideale Erg\u00e4nzung zum Kurs Nervensystem A, muss jedoch nicht in Folge besucht werden.<\/p>\n<h2>Bemerkung<\/h2>\n<p>21 Std. Fortbildung, EMR\/ASCA konform.<\/p>\n<h2>Mitbringen<\/h2>\n<ul>\n<li>empfohlenes Lehrbuch: Elvira Bierbach: Naturheilpraxis heute &#8211; LEHRBUCH und ATLAS. Achtung: Bitte NICHT das gleichnamige REPETITORIUM kaufen!<\/li>\n<li>Zur Vertiefung auf Wunsch: &#8220;Trailguide Anatomy&#8221; von Andrew Biel.<br \/>\nWer das Buch &#8220;Mensch, K\u00f6rper, Krankheit&#8221; hat, kann ebenfalls damit arbeiten.<\/li>\n<li>Empfohlene Apps: Visible Body Atlas oder Anatomie Atlas App, 3D-Brain App &amp; Pschyrembel App &#8211; wer sie hat oder kaufen m\u00f6chte, bitte mitbringen.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.icloud.com\/pages\/000dAu9WrL7ixA193sG10SoUw#KursbestWasMitbringen\" target=\"_blank\">Weitere Info zur empfohlenen Literatur, Apps und Kursmaterial<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medizinische Grundlagen 2 &#8211; Nervensystem B Lerninhalte In diesem Kurs erg\u00e4nzen wir unser inneres Bild aus dem Kurs Nervensystems A um die Blut- und Liquorzirkulation, die Hirnnerven und die Sinnesorgane, inkl. der Haut. Was passiert bei einem Hirnschlag? Was tut eigentlich weh bei Kopfschmerzen? Auch die Anatomie der Sinnesorgane leiten wir aus der Embryologie her, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-159751","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MG 2 - Nervensystem B | Wetzikon-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MG 2 - Nervensystem B | Wetzikon-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"Medizinische Grundlagen 2 &#8211; Nervensystem B Lerninhalte In diesem Kurs erg\u00e4nzen wir unser inneres Bild aus dem Kurs Nervensystems A um die Blut- und Liquorzirkulation, die Hirnnerven und die Sinnesorgane, inkl. der Haut. Was passiert bei einem Hirnschlag? Was tut eigentlich weh bei Kopfschmerzen? Auch die Anatomie der Sinnesorgane leiten wir aus der Embryologie her, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:04:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-nervensystem-b-wetzikon-en-27850012\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-nervensystem-b-wetzikon-en-27850012\\\/\",\"name\":\"MG 2 - Nervensystem B | Wetzikon-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-03-31T10:04:58+00:00\",\"dateModified\":\"2026-05-13T01:04:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-nervensystem-b-wetzikon-en-27850012\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-nervensystem-b-wetzikon-en-27850012\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-nervensystem-b-wetzikon-en-27850012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MG 2 &#8211; Nervensystem B | Wetzikon&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MG 2 - Nervensystem B | Wetzikon-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/","og_locale":"en_US","og_type":"article","og_title":"MG 2 - Nervensystem B | Wetzikon-en - Kientalerhof","og_description":"Medizinische Grundlagen 2 &#8211; Nervensystem B Lerninhalte In diesem Kurs erg\u00e4nzen wir unser inneres Bild aus dem Kurs Nervensystems A um die Blut- und Liquorzirkulation, die Hirnnerven und die Sinnesorgane, inkl. der Haut. Was passiert bei einem Hirnschlag? Was tut eigentlich weh bei Kopfschmerzen? Auch die Anatomie der Sinnesorgane leiten wir aus der Embryologie her, [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/","og_site_name":"Kientalerhof","article_modified_time":"2026-05-13T01:04:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/","name":"MG 2 - Nervensystem B | Wetzikon-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-03-31T10:04:58+00:00","dateModified":"2026-05-13T01:04:58+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-nervensystem-b-wetzikon-en-27850012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"MG 2 &#8211; Nervensystem B | Wetzikon&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/159751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=159751"}],"version-history":[{"count":1,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/159751\/revisions"}],"predecessor-version":[{"id":159758,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/159751\/revisions\/159758"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=159751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}