{"id":156227,"date":"2026-01-23T14:05:40","date_gmt":"2026-01-23T13:05:40","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/geistiges-heilen-teil-iii-en\/"},"modified":"2026-05-13T03:04:02","modified_gmt":"2026-05-13T01:04:02","slug":"geistiges-heilen-teil-iii-en-30107028","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/","title":{"rendered":"Geistiges Heilen Teil III&#8211;en"},"content":{"rendered":"<h3>Wir Menschen verf\u00fcgen \u00fcber viele Gaben. <\/h3>\n<p>Oftmals sind wir uns deren nicht oder nur wenig bewusst. Mit der Gabe des Geistigen Heilens verh\u00e4lt es sich oft \u00e4hnlich. In diesem Lehrgang machen wir uns auf die Spur der Gabe des Heilens und Handauflegens, \u00f6ffnen uns f\u00fcr die heilende Kraft der Ber\u00fchrungen und lernen, wie wir diese in Alltag und Beruf anwenden k\u00f6nnen.<br \/>\nNeben einer Schulung und Sch\u00e4rfung der eigenen Wahrnehmung lernen die Teilnehmerinnen und Teilnehmer vor allem das Sein in voller Pr\u00e4senz, welches den Raum f\u00fcr Heilung schafft. Erreicht wird dieses durch K\u00f6rper\u00fcbungen, Meditationen, konkrete Praxis sowie durch regen Austausch untereinander.<br \/>\nInsgesamt ist der Lehrgang Heilen sehr interaktiv und enth\u00e4lt Live-\u00dcbungen. Er lebt von der Dynamik, den Prozessen und der Energie der Teilnehmenden. Somit ist der Kursinhalt im besten Sinne massgeschneidert und variabel.<br \/>\nDer erste Teil des Lehrganges Geistiges Heilen kann auch als Einf\u00fchrungs- und Kennenlern-Wochenende besucht werden, um zu entscheiden, ob weitere Teile davon gebucht werden m\u00f6chten. Die einzelnen Teile sind in aufsteigender Reihenfolge zu besuchen, da sie aufeinander aufbauen. Es ist m\u00f6glich, sich f\u00fcr jeden Teil einzeln anzumelden.<\/p>\n<h2>Teil III<\/h2>\n<p>(Voraussetzung: Geistiges Heilen Lehrgang Teil II)<br \/>\nWir vertiefen weiter unsere Wahrnehmungsf\u00e4higkeit. Wie nehme ich meine eigene Energie und die meines Gegen\u00fcbers wahr? Wie und wo darf diese noch mehr ins Fliessen kommen? Wir transformieren Blockaden, festigen fortlaufend unsere individuelle Art des Heilens und lernen so, darauf zu vertrauen.<\/p>\n<h2>Kursziele<\/h2>\n<ul>\n<li> Vertiefung der Themen aus Teil I &amp; II <\/li>\n<li> Intensives, praktisches \u00dcben: Durch gezielte und wiederholte \u00dcbungen <\/li>\n<li> Hindernisse im sch\u00f6pferischen Heilprozess, prozessorientierte Begleitung <\/li>\n<\/ul>\n<h2>Kurszeiten<\/h2>\n<p>Folgende Uhrzeiten gelten als ungef\u00e4hre Angabe. Die konkrete Anfangszeit wird jeweils vor Ort angegeben.<br \/>\n1. Tag: 20 &#8211; 21.30 Uhr<br \/>\n2. Tag: 9 &#8211; 12 \/ 14 &#8211; 18 \/ 20 &#8211; 21.30 Uhr<br \/>\n3. Tag: 9 &#8211; 12 Uhr<\/p>\n<h2>Bemerkung<\/h2>\n<p>14 Stunden Fortbildung pro Wochenende. <\/p>\n<h2>Mitnehmen<\/h2>\n<p>Bequeme Kleidung (wir bewegen uns etwas), Wasserflasche, evtl. Schreibzeug.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir Menschen verf\u00fcgen \u00fcber viele Gaben. Oftmals sind wir uns deren nicht oder nur wenig bewusst. Mit der Gabe des Geistigen Heilens verh\u00e4lt es sich oft \u00e4hnlich. In diesem Lehrgang machen wir uns auf die Spur der Gabe des Heilens und Handauflegens, \u00f6ffnen uns f\u00fcr die heilende Kraft der Ber\u00fchrungen und lernen, wie wir diese [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-156227","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geistiges Heilen Teil III-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geistiges Heilen Teil III-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"Wir Menschen verf\u00fcgen \u00fcber viele Gaben. Oftmals sind wir uns deren nicht oder nur wenig bewusst. Mit der Gabe des Geistigen Heilens verh\u00e4lt es sich oft \u00e4hnlich. In diesem Lehrgang machen wir uns auf die Spur der Gabe des Heilens und Handauflegens, \u00f6ffnen uns f\u00fcr die heilende Kraft der Ber\u00fchrungen und lernen, wie wir diese [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:04:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/geistiges-heilen-teil-iii-en-30107028\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/geistiges-heilen-teil-iii-en-30107028\\\/\",\"name\":\"Geistiges Heilen Teil III-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-01-23T13:05:40+00:00\",\"dateModified\":\"2026-05-13T01:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/geistiges-heilen-teil-iii-en-30107028\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/geistiges-heilen-teil-iii-en-30107028\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/geistiges-heilen-teil-iii-en-30107028\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geistiges Heilen Teil III&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geistiges Heilen Teil III-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/","og_locale":"en_US","og_type":"article","og_title":"Geistiges Heilen Teil III-en - Kientalerhof","og_description":"Wir Menschen verf\u00fcgen \u00fcber viele Gaben. Oftmals sind wir uns deren nicht oder nur wenig bewusst. Mit der Gabe des Geistigen Heilens verh\u00e4lt es sich oft \u00e4hnlich. In diesem Lehrgang machen wir uns auf die Spur der Gabe des Heilens und Handauflegens, \u00f6ffnen uns f\u00fcr die heilende Kraft der Ber\u00fchrungen und lernen, wie wir diese [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/","og_site_name":"Kientalerhof","article_modified_time":"2026-05-13T01:04:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/","name":"Geistiges Heilen Teil III-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-01-23T13:05:40+00:00","dateModified":"2026-05-13T01:04:02+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/geistiges-heilen-teil-iii-en-30107028\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Geistiges Heilen Teil III&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/156227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=156227"}],"version-history":[{"count":2,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/156227\/revisions"}],"predecessor-version":[{"id":158895,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/156227\/revisions\/158895"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=156227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}