{"id":155807,"date":"2026-01-23T14:02:27","date_gmt":"2026-01-23T13:02:27","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/zapchen-stressregulation-en\/"},"modified":"2026-05-13T03:02:04","modified_gmt":"2026-05-13T01:02:04","slug":"zapchen-stressregulation-en-27580163","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/","title":{"rendered":"Zapchen &#8211; Stressregulation&#8211;en"},"content":{"rendered":"<h3>Zapchen ist eine einfache, k\u00f6rperbezogene, humorvolle und spielerische, therapeutisch wirksame Arbeitsweise.<\/h3>\n<p>Sie wurde von Julie Henderson (Napa\/Kalifornien) aus dem Wissen und K\u00f6nnen westlicher Psycho- und K\u00f6rperpsychotherapie, der Hypnotherapie nach Milton Erickson, den Erkenntnissen der Neurobiologie und dem jahrhundertealten Erfahrungswissen des tibetischen Vajrayana-Buddhismus \u00fcber die K\u00f6rper-Geist-Einheit entwickelt.<\/p>\n<p>In den \u00dcbungen nutzen wir Bewegung, Atmung, Stimme und Ber\u00fchrung als M\u00f6glichkeiten unseres K\u00f6rpers, inmitten der allt\u00e4glichen Anforderungen immer wieder zu gr\u00f6\u00dftm\u00f6glichem Wohlgef\u00fchl und zur Selbstachtsamkeit zur\u00fcckzukehren. Ein Wohlbefinden, das mehr umfasst als sich wohl zu f\u00fchlen \u2013 es bezieht sich auf einen grundlegenden Zustand der Entspannung und Leichtigkeit im Sein. Dabei verlagert sich unser normaler Zustand allm\u00e4hlich mehr in Richtung eines stabileren Wohlgef\u00fchls.<\/p>\n<p>Die \u00dcbungen, die uns im Grunde tief vertraut sind, sind eine unerwartet einfache Einladung an uns als K\u00f6rper\/Energie\/Bewusstheit, die uns innewohnende Freude, Pr\u00e4senz und Gelassenheit wieder zu erleben.<\/p>\n<p>Nicht nur sozial reagieren wir eingebunden in Systeme, auch unser K\u00f6rper ist in seiner Funktionsweise ein Zusammenspiel komplexer Systeme (z.B. Nervensystem, Blutkreislauf, hormonelle Regulierung, etc.). Unsere K\u00f6rpersysteme reagieren in fein abgestimmter Resonanz auf soziale und psychische Bedingungen und Erfahrungen. Mit einfachen Interventionen k\u00f6nnen wir diese Systeme in ihrer Regulationsf\u00e4higkeit und Flexibilit\u00e4t unterst\u00fctzen.<\/p>\n<h2>Was ist Zapchen?<\/h2>\n<p>Zapchen unterst\u00fctzt Ressourcenorientierung und St\u00e4rkung von Resilienz, hilft Burn-out vorzubeugen, unterst\u00fctzt Stabilisierung und Flexibilisierung von Grenzen und tiefe Vertrauensbildung im Kontakt.<br \/>\nDie Methode ist bew\u00e4hrt als Psychohygiene- und Selbstf\u00fcrsorgeverfahren im beratenden, therapeutischen und supervisorischen Setting. Die \u00dcbungen k\u00f6nnen auch im Einzel- und Gruppensetting zur Steigerung von Pr\u00e4senz und Selbstachtsamkeit eingesetzt werden.<\/p>\n<p>In jedem der Seminare praktizieren wir die Basics, die Grund\u00fcbungen des Zapchen, die jedes \u00dcben begleiten. Sie sind leicht in den Alltag zu integrierende \u00dcbungen, die helfen, neue Gewohnheiten zu entwickeln, um Stress abzubauen und Belastung zu vermindern und die zu einem gr\u00f6\u00dferen spontanen Wohlgef\u00fchl beitragen. Die Basics vertiefen sich nach und nach und werden allm\u00e4hlich integraler Bestandteil unseres Alltags.<\/p>\n<p><strong>H\u00f6r rein in die Podcasts mit Cornalia<\/strong><\/p>\n<p><a href=\"https:\/\/www.carl-auer.de\/magazin\/neuigkeiten\/cornelia-hammer-zapchen-somatics-entspannung-staerkung-resilienz\" target=\"_blank\">Podcast: Zapchen Somantics: Entspannung, St\u00e4rkung, Resilienz<\/a><br \/>\n<a href=\"https:\/\/www.carl-auer.de\/magazin\/sounds-of-science\/sounds-of-science-cornelia-hammer-tiefere-dimensionen-von-zapchen-1\" target=\"_blank\">Podcast: Tiefere Dimensionen von Zapchen 1<\/a><\/p>\n<h2>Die vier Kurse<\/h2>\n<p>In allen Zapchen-Kursen von Cornelia Hammer werden immer die Grund\u00fcbungen vermittelt. Pro Kurs werden zudem weitere \u00dcbungen jeweils zu einem bestimmten Themengebiet praktiziert<\/p>\n<h2>Die gemeinsamen Inhalte aller vier Kurse<\/h2>\n<ul>\n<li> Der Kurs ist eine Einladung mit Humor und Leichtigkeit das eigene Wohlgef\u00fchl zu unterst\u00fctzen. <\/li>\n<li>Im Kurs werden die &#8220;Basics\u201c, die Grund\u00fcbungen von Zapchen somatics, praktiziert. <\/li>\n<li>Hintergr\u00fcnde der &#8220;Basics\u201cwerden vermittelt. <\/li>\n<li>Anwendungsm\u00f6glichkeiten der &#8220;Basics\u201cwerden vermittelt. <\/li>\n<\/ul>\n<h2>Die gemeinsamen Ziele aller vier Kurse<\/h2>\n<ul>\n<li>k\u00f6rpereigene Stressregulationsmechanismen sind verstehbar und k\u00f6nnen auch im Alltag unterst\u00fctzt werden. <\/li>\n<li>einfache Wege zu Leichtigkeit und Wohlbefinden &#8220;inmitten von allem\u201c \u00f6ffnen sich. <\/li>\n<li>einfache, schlichte Lebendigkeit im Moment taucht auf. <\/li>\n<\/ul>\n<h2>Spezifische Inhalte &amp; Ziele des jeweiligen Teils<\/h2>\n<h3>K\u00f6rperpr\u00e4senz<\/h3>\n<ul>\n<li>\u00dcbungen zur K\u00f6rperpr\u00e4senz werden praktiziert. Dabei laden wir unseren K\u00f6rper in seinen verschiedenen Schichten zur Pr\u00e4senz im Moment ein. <\/li>\n<\/ul>\n<h3>Atem<\/h3>\n<ul>\n<li>Verschiedene Atem\u00fcbungen laden ein in tiefe Entspannung, in einfaches So-Sein und in Unterst\u00fctzung innerer Gelassenheit. <\/li>\n<li>\u00fcber unseren eigenen Atem \u00f6ffnen sich R\u00e4ume des Seins, die uns Geborgenheit und Zuflucht sind<\/li>\n<\/ul>\n<h3>Stressregulation<\/h3>\n<ul>\n<li>Die inneren Stresssysteme des K\u00f6rpers werden mit einfachen \u00dcbungen zu Regulation und Flexibilisierung eingeladen. <\/li>\n<li>das k\u00f6rpereigene Stresssystem kann mit einfachen Mitteln reguliert und stabilisiert werden. <\/li>\n<li>Sich sinken lassen ins Sein im Moment wird m\u00f6glich<\/li>\n<\/ul>\n<h3>Vertiefung<\/h3>\n<ul>\n<li>wir lassen uns tiefer in unser K\u00f6rperSein sinken und regenerieren von da aus. <\/li>\n<li>wir genie\u00dfen wohlw\u00fcnschende Ber\u00fchrung in Pr\u00e4senz mit hohem Respekt f\u00fcr Grenzen<\/li>\n<\/ul>\n<h3>Kursziele, des verl\u00e4ngerten, vierten Workshops:<\/h3>\n<ul>\n<li>Regeneration und Erholung<\/li>\n<li>Sich sinken lassen ins Sein im Moment<\/li>\n<li>gute Gesellschaft genie\u00dfen<\/li>\n<li>Verbundenheit erleben<\/li>\n<li>Wohlgef\u00fchl &#8220;inmitten von allem\u201c<\/li>\n<\/ul>\n<h2>Voraussetzungen<\/h2>\n<p>Keine. Jeder Mensch ist willkommen.<\/p>\n<h2>Mitbringen<\/h2>\n<p>Bewegungsfreundliche Kleidung, eventuell eigene Decke (es gibt auch welche vor Ort), Wasserflasche.<\/p>\n<h2>Kurszeiten<\/h2>\n<p>Ankunftstag: Beginn mit Abendessen um 18:30 Uhr, Abendsession: 19.30-21.30 Uhr<br \/>\nVolle(r) Tag(e): Morgenmeditation 30 Minuten, 9.00 Uhr-12.15 Uhr Kurszeit (incl. 15 Minuten Pause), 15.00-18.15 Uhr Kurszeit (incl. 15 Minuten Pause)<br \/>\nAbreisetag: Morgenmeditation 30 Minuten, 9.00 Uhr-12.15 Uhr Kurszeit (incl. 15 Minuten Pause)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zapchen ist eine einfache, k\u00f6rperbezogene, humorvolle und spielerische, therapeutisch wirksame Arbeitsweise. Sie wurde von Julie Henderson (Napa\/Kalifornien) aus dem Wissen und K\u00f6nnen westlicher Psycho- und K\u00f6rperpsychotherapie, der Hypnotherapie nach Milton Erickson, den Erkenntnissen der Neurobiologie und dem jahrhundertealten Erfahrungswissen des tibetischen Vajrayana-Buddhismus \u00fcber die K\u00f6rper-Geist-Einheit entwickelt. In den \u00dcbungen nutzen wir Bewegung, Atmung, Stimme und [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-155807","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zapchen - Stressregulation-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zapchen - Stressregulation-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"Zapchen ist eine einfache, k\u00f6rperbezogene, humorvolle und spielerische, therapeutisch wirksame Arbeitsweise. Sie wurde von Julie Henderson (Napa\/Kalifornien) aus dem Wissen und K\u00f6nnen westlicher Psycho- und K\u00f6rperpsychotherapie, der Hypnotherapie nach Milton Erickson, den Erkenntnissen der Neurobiologie und dem jahrhundertealten Erfahrungswissen des tibetischen Vajrayana-Buddhismus \u00fcber die K\u00f6rper-Geist-Einheit entwickelt. In den \u00dcbungen nutzen wir Bewegung, Atmung, Stimme und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:02:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/zapchen-stressregulation-en-27580163\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/zapchen-stressregulation-en-27580163\\\/\",\"name\":\"Zapchen - Stressregulation-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-01-23T13:02:27+00:00\",\"dateModified\":\"2026-05-13T01:02:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/zapchen-stressregulation-en-27580163\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/zapchen-stressregulation-en-27580163\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/zapchen-stressregulation-en-27580163\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zapchen &#8211; Stressregulation&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zapchen - Stressregulation-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/","og_locale":"en_US","og_type":"article","og_title":"Zapchen - Stressregulation-en - Kientalerhof","og_description":"Zapchen ist eine einfache, k\u00f6rperbezogene, humorvolle und spielerische, therapeutisch wirksame Arbeitsweise. Sie wurde von Julie Henderson (Napa\/Kalifornien) aus dem Wissen und K\u00f6nnen westlicher Psycho- und K\u00f6rperpsychotherapie, der Hypnotherapie nach Milton Erickson, den Erkenntnissen der Neurobiologie und dem jahrhundertealten Erfahrungswissen des tibetischen Vajrayana-Buddhismus \u00fcber die K\u00f6rper-Geist-Einheit entwickelt. In den \u00dcbungen nutzen wir Bewegung, Atmung, Stimme und [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/","og_site_name":"Kientalerhof","article_modified_time":"2026-05-13T01:02:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/","name":"Zapchen - Stressregulation-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-01-23T13:02:27+00:00","dateModified":"2026-05-13T01:02:04+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/zapchen-stressregulation-en-27580163\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Zapchen &#8211; Stressregulation&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=155807"}],"version-history":[{"count":1,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155807\/revisions"}],"predecessor-version":[{"id":156995,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155807\/revisions\/156995"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=155807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}