{"id":155803,"date":"2026-01-23T14:02:20","date_gmt":"2026-01-23T13:02:20","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/energetische-massage-fortgeschrittene-en\/"},"modified":"2026-07-15T03:01:32","modified_gmt":"2026-07-15T01:01:32","slug":"energetische-massage-fortgeschrittene-en-27200110","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/","title":{"rendered":"Energetische Massage Fortgeschrittene&#8211;en"},"content":{"rendered":"<p><strong>Energetische Massage ist eine heilende K\u00f6rperarbeit mit und ohne Ber\u00fchrung, die direkt in allen Schichten des Energiek\u00f6rpers und dem physischen K\u00f6rper wirksam ist. Sie wurde 1980 am Esalen Institut in Big Sur, Kalifornien, \u00fcber das brasilianische Trancemedium Luiz Gasparetto in die Welt gebracht und von der Brasilianerin Maria Lucia Bittencourt Sauer \u00fcber 35 Jahre lang praktiziert, weiterentwickelt und international verbreitet. Schahila Ute Albrecht hat als enge Vertraute von Maria Lucia 18 Jahre die Energetische Massage international studiert und praktiziert. Schahila leitet die Kurse in Energetischer Massage im deutschsprachigen Raum.<\/strong><\/p>\n<p>Energetische Massage ist eine sanfte und zugleich hochwirksame K\u00f6rperarbeit, die auf alle Ebenen k\u00f6rperlichen Seins l\u00f6send, reinigend und kr\u00e4ftigend einwirkt. Eine Sitzung in Energetischer Massage findet am bekleideten K\u00f6rper auf dem Massagetisch mit direkter und indirekter Ber\u00fchrung \u00fcber die H\u00e4nde statt. <\/p>\n<p>In diesem Workshop wird die erweiterte Technik der Energetischen Massage erlernt und alles, was gebraucht wird, um den Weg als Praktizierende\/r der Energetichen Massage weiter und gefestigter beschreiten zu k\u00f6nnen. <\/p>\n<p>Der Fortgeschrittenen-Kurs kann nur belegt werden, nachdem mindestens ein Einf\u00fchrungs- oder Basiskurs in Energetischer Massage besucht wurde. Die praktische Erfahrung wird im Kurs vertieft, so dass K\u00f6rper und Seele sich wieder erinnern und f\u00fcr neue Erfahrungen \u00f6ffnen k\u00f6nnen. Es wird in das feine energetische Arbeiten am R\u00fccken eingef\u00fchrt. Dies verst\u00e4rkt und unterst\u00fctzt die selbstheilenden Prozesse, die in einer Sitzung geweckt werden. <\/p>\n<p>Die fortgeschrittene Energetische Massage beinhaltet:<\/p>\n<ul>\n<li>Vertiefung der Energetischen Massage und zunehmende Verankerung im eigenen K\u00f6rper<\/li>\n<li>die Technik f\u00fcr das energetische Arbeiten am R\u00fccken kennenlernen<\/li>\n<li>die erweiterte Technik der Energetischen Massage in praktischer Anwendung erfahren und vertiefen \u2013 Integration<\/li>\n<li>den Fokus von Absicht im eigenen Herzen vertieft sp\u00fcren zu lernen und klarer in der inneren Ausrichtung zu werden<\/li>\n<li>das Vertrauen ins eigene Sp\u00fcren zu vertiefen, so dass innewohnende spezifische F\u00e4higkeiten und Kapazit\u00e4ten sich zeigen, entfalten und integrieren k\u00f6nnen<\/li>\n<li>darin zu reifen, Experte f\u00fcr sich selbst zu sein und nicht f\u00fcr die andere Person<\/li>\n<li>zu lernen, dass Heilung \u00fcblicherweise ein langsamer Prozess ist. Wie kann genug Raum gegeben werden, damit sich die selbstheilenden Prozesse gr\u00f6sstm\u00f6glich entfalten k\u00f6nnen<\/li>\n<li>die Selbstheilung unterst\u00fctzende Quellen der Kraft und Liebe aus anderen Dimensionen in sicherem Feld erfahren lernen. Sich in eigenem Tempo daf\u00fcr \u00f6ffnen<\/li>\n<li>unterst\u00fctzende Methoden kennenlernen, um pr\u00e4senter sein zu k\u00f6nnen: Meditation, Einf\u00fchrung in schamanische Traumzeit, sanfte K\u00f6rper\u00fcbungen, verschiedene Arten energetischer Reinigung<\/li>\n<\/ul>\n<p>Mit fortlaufender \u00dcbung und Erfahrung werden wir \u00fcber die Anwendung der Energetischen Massage auch vertraut mit den naturkosmischen Gesetzm\u00e4ssigkeiten einer erweiterten Wirklichkeit, die uns innerlich wachsen und reifen lassen.<\/p>\n<h2>Zielgruppe<\/h2>\n<p>Nach Besuch eines oder mehrerer Basiskurse ist dieser Fortgeschrittenen-Kurs offen f\u00fcr Teilnehmende jeder Altersgruppe. Er kann sowohl von TherapeutInnen und K\u00f6rpertherapeutInnen aller Fachrichtungen wie auch von nicht therapeutisch T\u00e4tigen f\u00fcr eine vertiefende Selbstheilung und zur pers\u00f6nlichen Entfaltung belegt werden.<\/p>\n<h2>Voraussetzungen<\/h2>\n<p>Der Fortgeschrittenen-Kurs kann nur belegt werden, nachdem mindestens ein Einf\u00fchrungs- oder Basiskurs in Energetischer Massage besucht wurde.<\/p>\n<h2>Bemerkung<\/h2>\n<p>32 Std. Fortbildung, EMR \/ASCA konform.<\/p>\n<h2>Kurszeiten<\/h2>\n<p>Mo 15 &#8211; 18 \/ 20 &#8211; 22 Uhr<br \/>\nDi 9:30 &#8211; 12:30 \/ 15:30 &#8211; 18:30 \/ 20 &#8211; 22 Uhr<br \/>\nMi 9:30 &#8211; 12:30 \/ 15:30 &#8211; 18:30 \/ 20 &#8211; 22 Uhr<br \/>\nDo 9:30 &#8211; 12:30 \/ 15:30 &#8211; 18:30 \/ 20 &#8211; 22 Uhr<br \/>\nFr 9:30 &#8211; 12:30 Uhr<\/p>\n<h2>Weitere Informationen<\/h2>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=vowHfEN8fIY\" target=\"_blank\">Video Energetische Massage mit Schahila Albrecht<\/a><br \/>\nArtikel von Maria Lucia Bittencourt-Sauer \u00fcber <a href=\"http:\/\/www.kientalerhof.ch\/cms\/wp-content\/uploads\/2014\/05\/Kientalerhof_Kurs_Energetische_Massage_Weitere_Informationen.pdf\" target=\"_blank\">Die Reise vom Verstand zum Herzen (PDF)<\/a><\/p>\n<h2>Einzelsitzungen in Energetischer Massage mit Schahila Ute Albrecht<\/h2>\n<p>W\u00e4hrend der Zeit des Basis- und Fortgeschrittenen-Kurses steht Schahila Ute Albrecht zus\u00e4tzlich f\u00fcr Einzelsitzungen in Energetischer Massage zur Verf\u00fcgung.<br \/>\nN\u00e4here Informationen und Terminabsprachen im Kientalerhof unter Telefon: +41 33 676 26 76.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Energetische Massage ist eine heilende K\u00f6rperarbeit mit und ohne Ber\u00fchrung, die direkt in allen Schichten des Energiek\u00f6rpers und dem physischen K\u00f6rper wirksam ist. Sie wurde 1980 am Esalen Institut in Big Sur, Kalifornien, \u00fcber das brasilianische Trancemedium Luiz Gasparetto in die Welt gebracht und von der Brasilianerin Maria Lucia Bittencourt Sauer \u00fcber 35 Jahre lang [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-155803","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energetische Massage Fortgeschrittene-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energetische Massage Fortgeschrittene-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"Energetische Massage ist eine heilende K\u00f6rperarbeit mit und ohne Ber\u00fchrung, die direkt in allen Schichten des Energiek\u00f6rpers und dem physischen K\u00f6rper wirksam ist. Sie wurde 1980 am Esalen Institut in Big Sur, Kalifornien, \u00fcber das brasilianische Trancemedium Luiz Gasparetto in die Welt gebracht und von der Brasilianerin Maria Lucia Bittencourt Sauer \u00fcber 35 Jahre lang [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T01:01:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/energetische-massage-fortgeschrittene-en-27200110\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/energetische-massage-fortgeschrittene-en-27200110\\\/\",\"name\":\"Energetische Massage Fortgeschrittene-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-01-23T13:02:20+00:00\",\"dateModified\":\"2026-07-15T01:01:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/energetische-massage-fortgeschrittene-en-27200110\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/energetische-massage-fortgeschrittene-en-27200110\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/energetische-massage-fortgeschrittene-en-27200110\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energetische Massage Fortgeschrittene&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energetische Massage Fortgeschrittene-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/","og_locale":"en_US","og_type":"article","og_title":"Energetische Massage Fortgeschrittene-en - Kientalerhof","og_description":"Energetische Massage ist eine heilende K\u00f6rperarbeit mit und ohne Ber\u00fchrung, die direkt in allen Schichten des Energiek\u00f6rpers und dem physischen K\u00f6rper wirksam ist. Sie wurde 1980 am Esalen Institut in Big Sur, Kalifornien, \u00fcber das brasilianische Trancemedium Luiz Gasparetto in die Welt gebracht und von der Brasilianerin Maria Lucia Bittencourt Sauer \u00fcber 35 Jahre lang [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/","og_site_name":"Kientalerhof","article_modified_time":"2026-07-15T01:01:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/","name":"Energetische Massage Fortgeschrittene-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-01-23T13:02:20+00:00","dateModified":"2026-07-15T01:01:32+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/energetische-massage-fortgeschrittene-en-27200110\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Energetische Massage Fortgeschrittene&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=155803"}],"version-history":[{"count":1,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155803\/revisions"}],"predecessor-version":[{"id":156989,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155803\/revisions\/156989"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=155803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}