{"id":155769,"date":"2026-01-23T14:02:05","date_gmt":"2026-01-23T13:02:05","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en\/"},"modified":"2026-05-13T03:01:55","modified_gmt":"2026-05-13T01:01:55","slug":"modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/","title":{"rendered":"Modul 5: FT2 Gruppenph\u00e4nomene und Setting &#8211; Holotropes Atmen&#8211;en"},"content":{"rendered":"<p><!-- Kurskosten nicht anzeigen --><!-- Kurtaxe nicht anzeigen --><!-- Rentout mit Zimmerreservation --><\/p>\n<h3>Seminar eines externen Anbieters<\/h3>\n<p><strong>Seminar-Anmeldung<\/strong> &gt;&gt; direkt beim Veranstalter &gt;&gt; <a href=\"https:\/\/www.holotrop-atmen.ch\/unser-angebot\/kompetenztraining\" target=\"_blank\">www.holotrop-atmen.ch\/fachkompetenztraining<\/a>.<br \/>\n<strong>Zimmerreservierung<\/strong> &gt;&gt; im Kientalerhof nach Best\u00e4tigung des Veranstalters &gt;&gt; Knopf oben <strong>Zimmer reservieren<\/strong>. Diverse Kategorien inkl. Preise findest du unten in der Tabelle.<br \/>\n&nbsp;<\/p>\n<h2>Fachtraining 2 &#8211; Holotropes Atmen und spirituelle Praxis<\/h2>\n<p>Die Fachkompetenz Seminare bestehen aus 6 Modulen \u00e0 5 Tagen und 1 Abschlusspr\u00fcfung \u00e0 5 Tagen (je 48 AE) sowie zwei Supervisionen \u00e0 5 Tagen. Die Seminare folgen der inhaltlichen Grundstruktur von Holotropen Atemsitzungen und sind modular aufgebaut. Neben der Methodenkompetenz, werden jeweils 4 Atemprozesse erlebt, die der \u00dcbung, Praxiserfahrung und Vertiefung der Theorie dienen.<br \/>\nTherapeut:Innen oder Interessierten mit fachlichem Bezug k\u00f6nnen einzelne Fachkompetenzmodule (M1 &#8211; M4) individuell als Fortbildung buchen, ohne dass das komplette Fachtraining absolviert werden muss (EMR\/ASCA konform).<br \/>\nAlle Module sind ausf\u00fchrlich unter <a href=\"https:\/\/www.breath-essence.ch\" target=\"_blank\">www.breath-essence.ch<\/a> beschrieben. Die Modulreihe ist so gestaltet, dass die einzelnen Inhalte aufeinander aufbauen und die Kompetenz der vorherigen Module in den weiteren Modulen angewendet und vertieft wird.<br \/>\n<strong>Zu diesem Fachkompetenz Modul sind nur Teilnehmer zugelassen, die das gesamte Fachtraining besuchen (geschlossene Gruppe: Curriculum B).<\/strong><\/p>\n<h3>Themen und Termine dieser Fachkompetenz Seminar-Reihe:<\/h3>\n<p><strong>18.03. &#8211; 22.03.2026<\/strong> | Modul 1: Therapeutische Grundlagen<br \/>\n<strong>03.06. &#8211; 07.06.2026<\/strong> | Modul 2: K\u00f6rperarbeit und k\u00f6rpernahe Interventionen<br \/>\n<strong>12.08. &#8211; 16.08.2026<\/strong> | Modul 3: Musik in der Prozessarbeit<br \/>\n<strong>21.10. &#8211; 25.10.2026<\/strong> | Modul 4: Prozessbilder und Sharing<br \/>\n<strong>17.02. &#8211; 21.02.2027<\/strong> | Modul 5: Gruppenph\u00e4nomene und Setting<br \/>\n<strong>06.05. &#8211; 10.05.2027<\/strong> | Modul 6: Seminarleitung<br \/>\n<strong>08.07. &#8211; 12.07.2027<\/strong> |Modul 7: Abschlusspr\u00fcfung<\/p>\n<p><strong>Ebenfalls Teil des Fachtrainings sind zwei Supervisionen:<\/strong><br \/>\n<strong>30.08 \u2013 03.09.2028<\/strong> | Supervision 1: mit fallbezogenen Themen (Theorie)<br \/>\n<strong>15.11. \u2013 19.11.2028<\/strong> | Supervision 2: k\u00f6rperorientiert mit fallbezogenen Themen (Praxis)<\/p>\n<h2>Modul 5: Gruppenph\u00e4nomene und Setting <\/h2>\n<p> Wir lernen Gruppenprozesse und Gruppendynamiken kennen und orientieren uns an der ph\u00e4nomenologisch-k\u00f6rperorientierten Nachbearbeitung in der Gruppe. Wir betrachten verschiedene Blickwinkel (Ich \/ Du \/ Wir Perspektive) und lernen den peripheren Blick einer Gesamtgruppe kennen. Wir bearbeiten die Sitter-Atmer Dyade n\u00e4her und gehen auf besondere Ph\u00e4nomene in der Gruppe und in der Leitungsrolle ein. Wir besprechen das Set und Setting von Holotropen Atemsitzungen und stellen einen Katalog zusammen, was man zur Vorbereitung, Durchf\u00fchrung und Nachbearbeitung von Seminaren ben\u00f6tigt. Wir betrachten Ausschlussgr\u00fcnde von Holotropen Atemsitzungen und gehen auf medizinische Kontraindikationen n\u00e4her ein.<\/p>\n<ul>\n<li> Gruppenprozesse und Gruppendynamiken\n<ul>ph\u00e4nomenologisch-k\u00f6rperorientierten Nachbearbeitung in der Gruppe<\/p>\n<ul>Blickwinkel (Ich \/ Du \/ Wir Perspektive)<\/p>\n<ul>Die Sitter-Atmer Dyade<\/p>\n<ul>Ausschlussgr\u00fcnde und Kontraindikationen von Holotropen Atemsitzungen<\/p>\n<ul>Vorbereitung, Durchf\u00fchrung und Nachbearbeitung (Set und Setting)<\/li>\n<\/ul>\n<p>In jedem Kompetenzmodul steht der Erwerb der Fachkompetenz im Vordergrund. Um die Themen zu \u00fcben, werden mehrere Holotrope Atemsitzungen stattfinden, in denen die Gruppenteilnehmer abwechselnd in die therapeutische und die erfahrende Rolle schl\u00fcpfen. Die Theorie kann praktisch angewandt und vertieft werden. <\/p>\n<h2>Voraussetzungen<\/h2>\n<p> Normale k\u00f6rperliche Gesundheit. Geschlossene Gruppe: Curriculum B. <\/p>\n<h2>Bemerkungen<\/h2>\n<p>anrechenbar als Weiterbildung: 48 AE<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seminar eines externen Anbieters Seminar-Anmeldung &gt;&gt; direkt beim Veranstalter &gt;&gt; www.holotrop-atmen.ch\/fachkompetenztraining. Zimmerreservierung &gt;&gt; im Kientalerhof nach Best\u00e4tigung des Veranstalters &gt;&gt; Knopf oben Zimmer reservieren. Diverse Kategorien inkl. Preise findest du unten in der Tabelle. &nbsp; Fachtraining 2 &#8211; Holotropes Atmen und spirituelle Praxis Die Fachkompetenz Seminare bestehen aus 6 Modulen \u00e0 5 Tagen und 1 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-155769","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modul 5: FT2 Gruppenph\u00e4nomene und Setting - Holotropes Atmen-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modul 5: FT2 Gruppenph\u00e4nomene und Setting - Holotropes Atmen-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"Seminar eines externen Anbieters Seminar-Anmeldung &gt;&gt; direkt beim Veranstalter &gt;&gt; www.holotrop-atmen.ch\/fachkompetenztraining. Zimmerreservierung &gt;&gt; im Kientalerhof nach Best\u00e4tigung des Veranstalters &gt;&gt; Knopf oben Zimmer reservieren. Diverse Kategorien inkl. Preise findest du unten in der Tabelle. &nbsp; Fachtraining 2 &#8211; Holotropes Atmen und spirituelle Praxis Die Fachkompetenz Seminare bestehen aus 6 Modulen \u00e0 5 Tagen und 1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:01:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\\\/\",\"name\":\"Modul 5: FT2 Gruppenph\u00e4nomene und Setting - Holotropes Atmen-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-01-23T13:02:05+00:00\",\"dateModified\":\"2026-05-13T01:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modul 5: FT2 Gruppenph\u00e4nomene und Setting &#8211; Holotropes Atmen&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modul 5: FT2 Gruppenph\u00e4nomene und Setting - Holotropes Atmen-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/","og_locale":"en_US","og_type":"article","og_title":"Modul 5: FT2 Gruppenph\u00e4nomene und Setting - Holotropes Atmen-en - Kientalerhof","og_description":"Seminar eines externen Anbieters Seminar-Anmeldung &gt;&gt; direkt beim Veranstalter &gt;&gt; www.holotrop-atmen.ch\/fachkompetenztraining. Zimmerreservierung &gt;&gt; im Kientalerhof nach Best\u00e4tigung des Veranstalters &gt;&gt; Knopf oben Zimmer reservieren. Diverse Kategorien inkl. Preise findest du unten in der Tabelle. &nbsp; Fachtraining 2 &#8211; Holotropes Atmen und spirituelle Praxis Die Fachkompetenz Seminare bestehen aus 6 Modulen \u00e0 5 Tagen und 1 [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/","og_site_name":"Kientalerhof","article_modified_time":"2026-05-13T01:01:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/","name":"Modul 5: FT2 Gruppenph\u00e4nomene und Setting - Holotropes Atmen-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-01-23T13:02:05+00:00","dateModified":"2026-05-13T01:01:55+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/modul-5-ft2-gruppenphaenomene-und-setting-holotropes-atmen-en-ro-427007\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Modul 5: FT2 Gruppenph\u00e4nomene und Setting &#8211; Holotropes Atmen&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=155769"}],"version-history":[{"count":1,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155769\/revisions"}],"predecessor-version":[{"id":156955,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155769\/revisions\/156955"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=155769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}