{"id":155751,"date":"2026-01-23T14:01:58","date_gmt":"2026-01-23T13:01:58","guid":{"rendered":"https:\/\/kientalerhof.ch\/courses\/uncategorized\/mg-2-bewegungssystem-wetzikon-en\/"},"modified":"2026-05-13T03:01:50","modified_gmt":"2026-05-13T01:01:50","slug":"mg-2-bewegungssystem-wetzikon-en-27850002","status":"publish","type":"course","link":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/","title":{"rendered":"MG 2 &#8211; Bewegungssystem | Wetzikon&#8211;en"},"content":{"rendered":"<h3>Medizinische Grundlagen 2 &#8211; Bewegungssystem<\/h3>\n<h2>Kursinhalte<\/h2>\n<p>Das Urmodell f\u00fcr die festen K\u00f6rper aller Lebewesen ist die Kristallbildung: von der Cellulose im Holz, dem Kieselskelett des Strahlentierchens, dem Panzer des Seeigels bis letztlich zum Kalkgef\u00fcge des menschlichen Knochens. Dabei ist der Vorl\u00e4ufer des Knochens der Knorpel! Klar, denn das Leben hat sich zun\u00e4chst im Wasser abgespielt. Im Wasser? Ja, im Fruchtwasser des Mutterleibs beginnt unsere dynamische Reise des Bewegungs-Systems:<\/p>\n<p>Ertasten wichtiger Knochenpunkte zur Orientierung am K\u00f6rper, wichtige Sch\u00e4del-Knochen und Wirbel in der \u00dcbersicht. Erkennen der Merkmale, die ein freies Gelenk ausmachen. Was passiert eigentlich bei Arthrose oder bei der entz\u00fcndlichen Arthritis? Was bedeutet Rheuma?<br \/>\nDie Bewegungen in den grossen Gelenken von Arm und Bein werden durchgespielt, wichtige Skelettmuskeln beschrieben: Wo liegen sie? Kann ich sie sp\u00fcren? Sind sie tastbar? Welche Bewegungen in welchem Gelenk l\u00f6sen sie aus? Vergessen wir nicht, dass jeder Skelettmuskel mit seiner Sehne und der Faszienh\u00fclle ein feinf\u00fchliges Sinnesorgan ist, das f\u00fcr die Koordination von Bewegungen wichtig ist!<\/p>\n<h2>Kursziele<\/h2>\n<p>Die Teilnehmenden sind in der Lage<\/p>\n<ul>\n<li>das menschliche Skelett in einer Skizze (Modell 4-Beiner, Wirbeltier) zu beschreiben<\/li>\n<li>Analogien im Aufbau von Arm und Bein festzustellen<\/li>\n<li>vier Funktionen des Knochens zu beschreiben und daraus den Aufbau herzuleiten (Leichtbauweise-Spongiosa)<\/li>\n<li>f\u00fcnf Merkmale eines freien Gelenks aufzulisten<\/li>\n<li>f\u00fcnf Beschreibungsmerkmale eines Skelettmuskels aufzuz\u00e4hlen (&#8220;Steckbrief&#8221;)<\/li>\n<li>wichtige Knochenpunkte am eigenen K\u00f6rper aufzusp\u00fcren und zu benennen<\/li>\n<li>wichtige Skelettmuskeln zu beschreiben<\/li>\n<li>Bewegungen in den Gelenken der Extremit\u00e4ten zu benennen (Schulter\/H\u00fcfte, Knie\/Ellenbogen, Sprung-\/Handgelenke)<\/li>\n<li>Gelenke von Arm und Bein miteinander zu vergleichen.<\/li>\n<\/ul>\n<h2>Zielgruppe<\/h2>\n<p>Dieser Kurs richtet sich an angehende K\u00f6rpertherapeuten\/innen (Shiatsu, Craniosacral Therapie, Rebalancing, Massage, Akupressur u.a.) und weitere Interessierte. Die Inhalte entsprechen den Anforderungen des Schweizer Gesundheitswesens. F\u00fcr Menschen ohne medizinische Ausbildung ist dieses Seminar ein vortrefflicher Einstieg in die vielschichtige Welt der K\u00f6rperarbeit und ins anatomische Grundwissen. Medizinisch ausgebildete Personen k\u00f6nnen von der ganzheitlichen, Methoden \u00fcbergreifenden Sicht profitieren. <\/p>\n<h2>Bemerkung<\/h2>\n<p>21 Std. Fortbildung, EMR\/ASCA konform<\/p>\n<h2>Mitbringen<\/h2>\n<p>Laufschuhe, um das eigene Bewegungssystem in Schwung zu bringen.<br \/>\n<strong>Bitte Buntstifte aus Holz mitbringen!<\/strong><\/p>\n<h2>Weitere Informationen<\/h2>\n<p>Lehrbuch als Unterrichtsgrundlage: Elvira Bierbach: Naturheilpraxis heute &#8211; LEHRBUCH und ATLAS. Achtung: Bitte NICHT das gleichnamige REPETITORIUM kaufen!<br \/>\nZur Vertiefung auf Wunsch: &#8220;Trailguide Anatomy&#8221; von Andrew Biel<br \/>\nWer das Buch &#8220;Mensch, K\u00f6rper, Krankheit&#8221; hat, kann ebenfalls damit arbeiten.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medizinische Grundlagen 2 &#8211; Bewegungssystem Kursinhalte Das Urmodell f\u00fcr die festen K\u00f6rper aller Lebewesen ist die Kristallbildung: von der Cellulose im Holz, dem Kieselskelett des Strahlentierchens, dem Panzer des Seeigels bis letztlich zum Kalkgef\u00fcge des menschlichen Knochens. Dabei ist der Vorl\u00e4ufer des Knochens der Knorpel! Klar, denn das Leben hat sich zun\u00e4chst im Wasser abgespielt. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-155751","course","type-course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MG 2 - Bewegungssystem | Wetzikon-en - Kientalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MG 2 - Bewegungssystem | Wetzikon-en - Kientalerhof\" \/>\n<meta property=\"og:description\" content=\"Medizinische Grundlagen 2 &#8211; Bewegungssystem Kursinhalte Das Urmodell f\u00fcr die festen K\u00f6rper aller Lebewesen ist die Kristallbildung: von der Cellulose im Holz, dem Kieselskelett des Strahlentierchens, dem Panzer des Seeigels bis letztlich zum Kalkgef\u00fcge des menschlichen Knochens. Dabei ist der Vorl\u00e4ufer des Knochens der Knorpel! Klar, denn das Leben hat sich zun\u00e4chst im Wasser abgespielt. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/\" \/>\n<meta property=\"og:site_name\" content=\"Kientalerhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:01:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-bewegungssystem-wetzikon-en-27850002\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-bewegungssystem-wetzikon-en-27850002\\\/\",\"name\":\"MG 2 - Bewegungssystem | Wetzikon-en - Kientalerhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\"},\"datePublished\":\"2026-01-23T13:01:58+00:00\",\"dateModified\":\"2026-05-13T01:01:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-bewegungssystem-wetzikon-en-27850002\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-bewegungssystem-wetzikon-en-27850002\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/courses\\\/Uncategorized\\\/mg-2-bewegungssystem-wetzikon-en-27850002\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MG 2 &#8211; Bewegungssystem | Wetzikon&#8211;en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"name\":\"Kientalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#organization\",\"name\":\"Kientalerhof\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"contentUrl\":\"https:\\\/\\\/kientalerhof.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/khh_logo_white.svg\",\"width\":594,\"height\":138,\"caption\":\"Kientalerhof\"},\"image\":{\"@id\":\"https:\\\/\\\/kientalerhof.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MG 2 - Bewegungssystem | Wetzikon-en - Kientalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/","og_locale":"en_US","og_type":"article","og_title":"MG 2 - Bewegungssystem | Wetzikon-en - Kientalerhof","og_description":"Medizinische Grundlagen 2 &#8211; Bewegungssystem Kursinhalte Das Urmodell f\u00fcr die festen K\u00f6rper aller Lebewesen ist die Kristallbildung: von der Cellulose im Holz, dem Kieselskelett des Strahlentierchens, dem Panzer des Seeigels bis letztlich zum Kalkgef\u00fcge des menschlichen Knochens. Dabei ist der Vorl\u00e4ufer des Knochens der Knorpel! Klar, denn das Leben hat sich zun\u00e4chst im Wasser abgespielt. [&hellip;]","og_url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/","og_site_name":"Kientalerhof","article_modified_time":"2026-05-13T01:01:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/","url":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/","name":"MG 2 - Bewegungssystem | Wetzikon-en - Kientalerhof","isPartOf":{"@id":"https:\/\/kientalerhof.ch\/en\/#website"},"datePublished":"2026-01-23T13:01:58+00:00","dateModified":"2026-05-13T01:01:50+00:00","breadcrumb":{"@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kientalerhof.ch\/en\/courses\/Uncategorized\/mg-2-bewegungssystem-wetzikon-en-27850002\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kientalerhof.ch\/en\/"},{"@type":"ListItem","position":2,"name":"MG 2 &#8211; Bewegungssystem | Wetzikon&#8211;en"}]},{"@type":"WebSite","@id":"https:\/\/kientalerhof.ch\/en\/#website","url":"https:\/\/kientalerhof.ch\/en\/","name":"Kientalerhof","description":"","publisher":{"@id":"https:\/\/kientalerhof.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kientalerhof.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kientalerhof.ch\/en\/#organization","name":"Kientalerhof","url":"https:\/\/kientalerhof.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","contentUrl":"https:\/\/kientalerhof.ch\/wp-content\/uploads\/2025\/12\/khh_logo_white.svg","width":594,"height":138,"caption":"Kientalerhof"},"image":{"@id":"https:\/\/kientalerhof.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/types\/course"}],"replies":[{"embeddable":true,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/comments?post=155751"}],"version-history":[{"count":1,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155751\/revisions"}],"predecessor-version":[{"id":156937,"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/course\/155751\/revisions\/156937"}],"wp:attachment":[{"href":"https:\/\/kientalerhof.ch\/en\/wp-json\/wp\/v2\/media?parent=155751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}